{"id":434,"date":"2017-08-05T18:19:58","date_gmt":"2017-08-05T16:19:58","guid":{"rendered":"https:\/\/staging.titelschutz.ch\/datenschutzbelehrung\/"},"modified":"2017-08-18T16:48:53","modified_gmt":"2017-08-18T14:48:53","slug":"datenschutzbelehrung","status":"publish","type":"page","link":"https:\/\/titelschutz.ch\/ar\/datenschutzbelehrung\/","title":{"rendered":"Datenschutzbelehrung"},"content":{"rendered":"<ul>\n<li><b>\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a<\/b><\/li>\n<\/ul>\n<ol>\n<li>\u064a\u062a\u0645 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0644\u0644\u0639\u0645\u064a\u0644 \u0648\u0641\u0642\u064b\u0627 \u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629 \u0648\u0642\u0648\u0627\u0646\u064a\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0639\u0646 \u0628\u064f\u0639\u062f \u0648\u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0623\u062d\u0643\u0627\u0645 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u064a\u0629 \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629.<\/li>\n<li>\u064a\u062a\u0645 \u062c\u0645\u0639 \u0648\u062a\u062e\u0632\u064a\u0646 \u0648\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062c\u0645\u064a\u0639 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062a\u0645 \u062c\u0645\u0639\u0647\u0627 \u0641\u064a \u0625\u0637\u0627\u0631 \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0639\u0642\u062f (\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062e\u0632\u0648\u0646) \u0648\u0643\u0630\u0644\u0643 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062a\u0645 \u0625\u0646\u0634\u0627\u0624\u0647\u0627 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 (\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062d\u0631\u0643\u0629) \u0644\u063a\u0631\u0636 \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0639\u0642\u062f \u0648\u0644\u063a\u0631\u0636 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0641\u0648\u0627\u062a\u064a\u0631. \u064a\u062a\u0645 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0625\u0636\u0627\u0641\u064a \u0648\u0641\u0642\u064b\u0627 \u0644\u0644\u0645\u0627\u062f\u0629 7 \u0627\u0644\u0641\u0642\u0631\u0629 2.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Datenschutz Der Umgang mit den pers\u00f6nlichen Daten des Kunden erfolgt in \u00dcbereinstimmung mit den relevanten Datenschutzgesetzen, Telemediengesetzen sowie sonstigen einschl\u00e4gigen gesetzlichen Datenschutzbestimmungen. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-434","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/pages\/434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/comments?post=434"}],"version-history":[{"count":0,"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/pages\/434\/revisions"}],"wp:attachment":[{"href":"https:\/\/titelschutz.ch\/ar\/wp-json\/wp\/v2\/media?parent=434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}