{"id":12472,"date":"2020-05-16T17:45:36","date_gmt":"2020-05-16T15:45:36","guid":{"rendered":"https:\/\/titelschutz.ch\/copyright\/tigerkaetzchen\/"},"modified":"2020-05-16T17:45:36","modified_gmt":"2020-05-16T15:45:36","slug":"tigerkaetzchen","status":"publish","type":"copyright","link":"https:\/\/titelschutz.ch\/it\/copyright\/tigerkaetzchen\/","title":{"rendered":"Tigerk\u00e4tzchen"},"template":"","class_list":["post-12472","copyright","type-copyright","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/copyright\/12472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/copyright"}],"about":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/types\/copyright"}],"version-history":[{"count":0,"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/copyright\/12472\/revisions"}],"wp:attachment":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/media?parent=12472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}