{"id":5633,"date":"2019-03-05T21:18:41","date_gmt":"2019-03-05T20:18:41","guid":{"rendered":"https:\/\/staging.titelschutz.ch\/copyright\/eigentlich-ein-schoenes-leben\/"},"modified":"2019-03-05T21:18:41","modified_gmt":"2019-03-05T20:18:41","slug":"eigentlich-ein-schoenes-leben","status":"publish","type":"copyright","link":"https:\/\/titelschutz.ch\/it\/copyright\/eigentlich-ein-schoenes-leben\/","title":{"rendered":"Eigentlich ein sch\u00f6nes Leben"},"template":"","class_list":["post-5633","copyright","type-copyright","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/copyright\/5633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/copyright"}],"about":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/types\/copyright"}],"version-history":[{"count":0,"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/copyright\/5633\/revisions"}],"wp:attachment":[{"href":"https:\/\/titelschutz.ch\/it\/wp-json\/wp\/v2\/media?parent=5633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}