{"id":528327,"date":"2022-08-09T11:30:19","date_gmt":"2022-08-09T09:30:19","guid":{"rendered":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke.jpg"},"modified":"2022-08-09T11:30:19","modified_gmt":"2022-08-09T09:30:19","slug":"schweizer-literaturgesellschaft-eindruecke","status":"inherit","type":"attachment","link":"https:\/\/titelschutz.ch\/pl\/schweizer-literaturgesellschaft-eindruecke\/","title":{"rendered":"Schweizer-Literaturgesellschaft-Eindruecke"},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-528327","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"47\" src=\"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-300x47.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-300x47.jpg 300w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-1024x159.jpg 1024w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-768x119.jpg 768w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-1536x239.jpg 1536w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-1000x155.jpg 1000w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-230x36.jpg 230w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-350x54.jpg 350w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-480x75.jpg 480w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-800x124.jpg 800w, https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke.jpg 1595w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1595,"height":248,"file":"2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke.jpg","filesize":50357,"sizes":{"medium":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-300x47.jpg","width":300,"height":47,"filesize":4557,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-300x47.jpg"},"large":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-1024x159.jpg","width":1024,"height":159,"filesize":34333,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-1024x159.jpg"},"thumbnail":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-150x150.jpg","width":150,"height":150,"filesize":6798,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-150x150.jpg"},"medium_large":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-768x119.jpg","width":768,"height":119,"filesize":21018,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-768x119.jpg"},"1536x1536":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-1536x239.jpg","width":1536,"height":239,"filesize":66943,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-1536x239.jpg"},"sydney-large-thumb":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-1000x155.jpg","width":1000,"height":155,"filesize":33685,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-1000x155.jpg"},"sydney-medium-thumb":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-550x248.jpg","width":550,"height":248,"filesize":34043,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-550x248.jpg"},"sydney-small-thumb":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-230x36.jpg","width":230,"height":36,"filesize":3225,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-230x36.jpg"},"sydney-service-thumb":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-350x54.jpg","width":350,"height":54,"filesize":5832,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-350x54.jpg"},"sydney-mas-thumb":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-480x75.jpg","width":480,"height":75,"filesize":9911,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-480x75.jpg"},"woocommerce_thumbnail":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-420x248.jpg","width":420,"height":248,"filesize":27796,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-420x248.jpg"},"woocommerce_single":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-800x124.jpg","width":800,"height":124,"filesize":22513,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-800x124.jpg"},"woocommerce_gallery_thumbnail":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-100x100.jpg","width":100,"height":100,"filesize":3631,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-100x100.jpg"},"sow-carousel-default":{"file":"Schweizer-Literaturgesellschaft-Eindruecke-272x182.jpg","width":272,"height":182,"filesize":13803,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke-272x182.jpg"},"full":{"file":"Schweizer-Literaturgesellschaft-Eindruecke.jpg","width":1595,"height":248,"mime_type":"image\/jpeg","source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/titelschutz.ch\/wp-content\/uploads\/2022\/08\/Schweizer-Literaturgesellschaft-Eindruecke.jpg","filename":"Schweizer-Literaturgesellschaft-Eindruecke.jpg","filesize":50357,"_links":{"self":[{"href":"https:\/\/titelschutz.ch\/pl\/wp-json\/wp\/v2\/media\/528327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/titelschutz.ch\/pl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/titelschutz.ch\/pl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/titelschutz.ch\/pl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/titelschutz.ch\/pl\/wp-json\/wp\/v2\/comments?post=528327"}]}}